{"id":25869,"date":"2022-10-07T11:21:11","date_gmt":"2022-10-07T09:21:11","guid":{"rendered":"https:\/\/www.oliociccolella.business\/?post_type=product&#038;p=25869"},"modified":"2026-01-16T17:10:41","modified_gmt":"2026-01-16T16:10:41","slug":"huile-d-olive-vierge-extra-biologique-coratina-et-ogliarola-barese-bag-in-box","status":"publish","type":"product","link":"https:\/\/www.oliociccolella.business\/fr\/vente-huile-d-olive-extra-vierge-italienne\/huile-d-olive-vierge-extra-biologique-coratina-et-ogliarola-barese-bag-in-box\/","title":{"rendered":"Organic Cru \u2013 Huile d\u2019olive vierge extra biologique \u2013 Coratina et Ogliarola barese &#8211; Bag in box"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft\" src=\"https:\/\/www.oliociccolella.business\/wp-content\/uploads\/2020\/04\/biol-2024_extra-gold-medal.png\" alt=\"\" width=\"150\" height=\"167\" \/><img loading=\"lazy\" decoding=\"async\" class=\"alignleft\" src=\"https:\/\/www.oliociccolella.business\/wp-content\/uploads\/2020\/04\/sol-d-oro-2024_special-mention.png\" alt=\"\" width=\"150\" height=\"167\" \/><img loading=\"lazy\" decoding=\"async\" class=\"alignleft\" style=\"color: #333333; font-style: normal; font-weight: 300;\" src=\"https:\/\/www.oliociccolella.business\/wp-content\/uploads\/2020\/04\/2-cuori-merum_resize.png\" alt=\"\" width=\"150\" height=\"167\" \/><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full\" src=\"https:\/\/www.oliociccolella.business\/wp-content\/uploads\/2020\/04\/2-foglie-rosse-gambero-rosso-2023.png\" alt=\"\" width=\"150\" height=\"167\" \/><img loading=\"lazy\" decoding=\"async\" class=\"alignleft\" src=\"https:\/\/www.oliociccolella.business\/wp-content\/uploads\/2020\/04\/der-feinschmecker.png\" alt=\"\" width=\"150\" height=\"167\" \/><img loading=\"lazy\" decoding=\"async\" class=\"alignleft\" src=\"https:\/\/www.oliociccolella.business\/wp-content\/uploads\/2023\/05\/EQOO_2stelle_2023.png\" alt=\"\" width=\"150\" height=\"167\" \/><img loading=\"lazy\" decoding=\"async\" class=\"alignleft\" src=\"https:\/\/www.oliociccolella.business\/wp-content\/uploads\/2020\/04\/gold-award-tokyo_olive-japan-2023.png\" alt=\"\" width=\"150\" height=\"167\" \/><\/p>\n<div style=\"clear: both;\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignright\" src=\"https:\/\/www.oliociccolella.business\/wp-content\/uploads\/2020\/04\/olio-biologico.png\" alt=\"\" width=\"120\" height=\"120\" \/><\/p>\n<p>&nbsp;<\/p>\n<p><strong>Huile extra vierge d\u2019olive 100% italienne<\/strong><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignright\" src=\"https:\/\/www.oliociccolella.business\/wp-content\/uploads\/2020\/04\/olio-biologico.png\" alt=\"\" width=\"120\" height=\"120\" \/><\/p>\n<p>La nouvelle <strong>Bag in Box<\/strong> prot\u00e8ge l\u2019huile par l\u2019oxyg\u00e8ne et par la lumi\u00e8re. Gr\u00e2ce \u00e0 la fermeture herm\u00e9tique, le sac en aluminium et le pratique robinet doseur emp\u00eachent \u00e0 l\u2019air d\u2019entrer et permettent de contr\u00f4ler pr\u00e9cis\u00e9ment l\u2019\u00e9coulement de l\u2019huile, tout en \u00e9vitant le gaspillage.<br \/>\n\u00c0 l\u2019int\u00e9rieur il y a <strong>Organic Cru<\/strong>, l\u2019huile d\u2019olive vierge extra biologique obtenue des varie\u0301te\u0301s Coratina et Ogliarola barese, cultive\u0301es, re\u0301colte\u0301es et broye\u0301es conforme\u0301ment au Re\u0300glement de l\u2019UE en matie\u0300re de production biologique.<br \/>\nIl s\u2019agit d\u2019un me\u0301lange extre\u0302mement e\u0301quilibre\u0301, avec un gou\u0302t dynamique, de l\u2019amertume et de l\u2019ardence le\u0301ge\u0300res et des notes d\u2019amande et de camomille. Ide\u0301ales pour exalter des plats a\u0300 base de poisson, de le\u0301gumes, de fromage frais et de la viande blanche.<\/p>\n<p><strong>Disponibles dans les formats 1l et 3l.<\/strong><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft\" src=\"https:\/\/www.oliociccolella.business\/wp-content\/uploads\/2020\/04\/biol-2024_extra-gold-medal.png\" alt=\"\" width=\"150\" height=\"167\" \/><img loading=\"lazy\" decoding=\"async\" class=\"alignleft\" src=\"https:\/\/www.oliociccolella.business\/wp-content\/uploads\/2020\/04\/sol-d-oro-2024_special-mention.png\" alt=\"\" width=\"150\" height=\"167\" \/><img loading=\"lazy\" decoding=\"async\" class=\"alignleft\" style=\"color: #333333; font-style: normal; font-weight: 300;\" src=\"https:\/\/www.oliociccolella.business\/wp-content\/uploads\/2020\/04\/2-cuori-merum_resize.png\" alt=\"\" width=\"150\" height=\"167\" \/><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full\" src=\"https:\/\/www.oliociccolella.business\/wp-content\/uploads\/2020\/04\/2-foglie-rosse-gambero-rosso-2023.png\" alt=\"\" width=\"150\" height=\"167\" \/><img loading=\"lazy\" decoding=\"async\" class=\"alignleft\" src=\"https:\/\/www.oliociccolella.business\/wp-content\/uploads\/2020\/04\/der-feinschmecker.png\" alt=\"\" width=\"150\" height=\"167\" \/><img loading=\"lazy\" decoding=\"async\" class=\"alignleft\" src=\"https:\/\/www.oliociccolella.business\/wp-content\/uploads\/2023\/05\/EQOO_2stelle_2023.png\" alt=\"\" width=\"150\" height=\"167\" \/><img loading=\"lazy\" decoding=\"async\" class=\"alignleft\" src=\"https:\/\/www.oliociccolella.business\/wp-content\/uploads\/2020\/04\/gold-award-tokyo_olive-japan-2023.png\" alt=\"\" width=\"150\" height=\"167\" \/><\/p>\n<div style=\"clear: both;\"><\/div>\n","protected":false},"featured_media":26672,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[386,434,426],"product_tag":[458,462],"class_list":["post-25869","product","type-product","status-publish","has-post-thumbnail","product_cat-blend-fr","product_cat-biologique","product_cat-bag-in-box-fr","product_tag-blend-fr","product_tag-cru-fr","pa_formato-3l-fr","pa_formato-1l-fr","bwa-has-label-scope","tm-no-options","first","instock","shipping-taxable","purchasable","product-type-variable","has-default-attributes"],"acf":[],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.oliociccolella.business\/fr\/vente-huile-d-olive-extra-vierge-italienne\/huile-d-olive-vierge-extra-biologique-coratina-et-ogliarola-barese-bag-in-box\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"fr_FR\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Olio Ciccolella | Olio EVO di qualit\u00e0 superiore\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Organic Cru \u2013 Huile d\u2019olive vierge extra biologique \u2013 Coratina et Ogliarola barese \u2013 Bag in box | Olio Ciccolella\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.oliociccolella.business\/fr\/vente-huile-d-olive-extra-vierge-italienne\/huile-d-olive-vierge-extra-biologique-coratina-et-ogliarola-barese-bag-in-box\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/www.oliociccolella.business\/wp-content\/uploads\/2022\/10\/olio-biologico-coratina-e-ogliarola-barese-bag-in-box-3litri.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/www.oliociccolella.business\/wp-content\/uploads\/2022\/10\/olio-biologico-coratina-e-ogliarola-barese-bag-in-box-3litri.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2022-10-07T09:21:11+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2026-01-16T16:10:41+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Organic Cru \u2013 Huile d\u2019olive vierge extra biologique \u2013 Coratina et Ogliarola barese \u2013 Bag in box | Olio Ciccolella\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.oliociccolella.business\/wp-content\/uploads\/2022\/10\/olio-biologico-coratina-e-ogliarola-barese-bag-in-box-3litri.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.oliociccolella.business\\\/fr\\\/vente-huile-d-olive-extra-vierge-italienne\\\/huile-d-olive-vierge-extra-biologique-coratina-et-ogliarola-barese-bag-in-box\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.oliociccolella.business\\\/fr\\\/#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.oliociccolella.business\\\/fr\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.oliociccolella.business\\\/fr\\\/shop\\\/#listItem\",\"name\":\"Shop\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.oliociccolella.business\\\/fr\\\/shop\\\/#listItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/www.oliociccolella.business\\\/fr\\\/shop\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.oliociccolella.business\\\/fr\\\/huile-d-olive-extra-vierge-italienne\\\/blend-fr\\\/#listItem\",\"name\":\"Coratina et Ogliarola barese\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.oliociccolella.business\\\/fr\\\/#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.oliociccolella.business\\\/fr\\\/huile-d-olive-extra-vierge-italienne\\\/blend-fr\\\/#listItem\",\"position\":3,\"name\":\"Coratina et Ogliarola barese\",\"item\":\"https:\\\/\\\/www.oliociccolella.business\\\/fr\\\/huile-d-olive-extra-vierge-italienne\\\/blend-fr\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.oliociccolella.business\\\/fr\\\/vente-huile-d-olive-extra-vierge-italienne\\\/huile-d-olive-vierge-extra-biologique-coratina-et-ogliarola-barese-bag-in-box\\\/#listItem\",\"name\":\"Organic Cru \\u2013 Huile d\\u2019olive vierge extra biologique \\u2013 Coratina et Ogliarola barese &#8211; Bag in box\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.oliociccolella.business\\\/fr\\\/shop\\\/#listItem\",\"name\":\"Shop\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.oliociccolella.business\\\/fr\\\/vente-huile-d-olive-extra-vierge-italienne\\\/huile-d-olive-vierge-extra-biologique-coratina-et-ogliarola-barese-bag-in-box\\\/#listItem\",\"position\":4,\"name\":\"Organic Cru \\u2013 Huile d\\u2019olive vierge extra biologique \\u2013 Coratina et Ogliarola barese &#8211; Bag in box\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.oliociccolella.business\\\/fr\\\/huile-d-olive-extra-vierge-italienne\\\/blend-fr\\\/#listItem\",\"name\":\"Coratina et Ogliarola barese\"}}]},{\"@type\":\"ItemPage\",\"@id\":\"https:\\\/\\\/www.oliociccolella.business\\\/fr\\\/vente-huile-d-olive-extra-vierge-italienne\\\/huile-d-olive-vierge-extra-biologique-coratina-et-ogliarola-barese-bag-in-box\\\/#itempage\",\"url\":\"https:\\\/\\\/www.oliociccolella.business\\\/fr\\\/vente-huile-d-olive-extra-vierge-italienne\\\/huile-d-olive-vierge-extra-biologique-coratina-et-ogliarola-barese-bag-in-box\\\/\",\"name\":\"Organic Cru \\u2013 Huile d\\u2019olive vierge extra biologique \\u2013 Coratina et Ogliarola barese \\u2013 Bag in box | Olio Ciccolella\",\"inLanguage\":\"fr-FR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.oliociccolella.business\\\/fr\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.oliociccolella.business\\\/fr\\\/vente-huile-d-olive-extra-vierge-italienne\\\/huile-d-olive-vierge-extra-biologique-coratina-et-ogliarola-barese-bag-in-box\\\/#breadcrumblist\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.oliociccolella.business\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/olio-biologico-coratina-e-ogliarola-barese-bag-in-box-3litri.jpg\",\"@id\":\"https:\\\/\\\/www.oliociccolella.business\\\/fr\\\/vente-huile-d-olive-extra-vierge-italienne\\\/huile-d-olive-vierge-extra-biologique-coratina-et-ogliarola-barese-bag-in-box\\\/#mainImage\",\"width\":800,\"height\":800},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.oliociccolella.business\\\/fr\\\/vente-huile-d-olive-extra-vierge-italienne\\\/huile-d-olive-vierge-extra-biologique-coratina-et-ogliarola-barese-bag-in-box\\\/#mainImage\"},\"datePublished\":\"2022-10-07T11:21:11+02:00\",\"dateModified\":\"2026-01-16T17:10:41+01:00\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.oliociccolella.business\\\/fr\\\/#organization\",\"name\":\"Olio Ciccolella\",\"description\":\"Olio EVO di qualit\\u00e0 superiore\",\"url\":\"https:\\\/\\\/www.oliociccolella.business\\\/fr\\\/\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.oliociccolella.business\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.oliociccolella.business\\\/fr\\\/\",\"name\":\"Olio Ciccolella\",\"description\":\"Olio EVO di qualit\\u00e0 superiore\",\"inLanguage\":\"fr-FR\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.oliociccolella.business\\\/fr\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Organic Cru \u2013 Huile d\u2019olive vierge extra biologique \u2013 Coratina et Ogliarola barese \u2013 Bag in box | Olio Ciccolella","description":"","canonical_url":"https:\/\/www.oliociccolella.business\/fr\/vente-huile-d-olive-extra-vierge-italienne\/huile-d-olive-vierge-extra-biologique-coratina-et-ogliarola-barese-bag-in-box\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/www.oliociccolella.business\/fr\/vente-huile-d-olive-extra-vierge-italienne\/huile-d-olive-vierge-extra-biologique-coratina-et-ogliarola-barese-bag-in-box\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.oliociccolella.business\/fr\/#listItem","position":1,"name":"Home","item":"https:\/\/www.oliociccolella.business\/fr\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.oliociccolella.business\/fr\/shop\/#listItem","name":"Shop"}},{"@type":"ListItem","@id":"https:\/\/www.oliociccolella.business\/fr\/shop\/#listItem","position":2,"name":"Shop","item":"https:\/\/www.oliociccolella.business\/fr\/shop\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.oliociccolella.business\/fr\/huile-d-olive-extra-vierge-italienne\/blend-fr\/#listItem","name":"Coratina et Ogliarola barese"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.oliociccolella.business\/fr\/#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.oliociccolella.business\/fr\/huile-d-olive-extra-vierge-italienne\/blend-fr\/#listItem","position":3,"name":"Coratina et Ogliarola barese","item":"https:\/\/www.oliociccolella.business\/fr\/huile-d-olive-extra-vierge-italienne\/blend-fr\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.oliociccolella.business\/fr\/vente-huile-d-olive-extra-vierge-italienne\/huile-d-olive-vierge-extra-biologique-coratina-et-ogliarola-barese-bag-in-box\/#listItem","name":"Organic Cru \u2013 Huile d\u2019olive vierge extra biologique \u2013 Coratina et Ogliarola barese &#8211; Bag in box"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.oliociccolella.business\/fr\/shop\/#listItem","name":"Shop"}},{"@type":"ListItem","@id":"https:\/\/www.oliociccolella.business\/fr\/vente-huile-d-olive-extra-vierge-italienne\/huile-d-olive-vierge-extra-biologique-coratina-et-ogliarola-barese-bag-in-box\/#listItem","position":4,"name":"Organic Cru \u2013 Huile d\u2019olive vierge extra biologique \u2013 Coratina et Ogliarola barese &#8211; Bag in box","previousItem":{"@type":"ListItem","@id":"https:\/\/www.oliociccolella.business\/fr\/huile-d-olive-extra-vierge-italienne\/blend-fr\/#listItem","name":"Coratina et Ogliarola barese"}}]},{"@type":"ItemPage","@id":"https:\/\/www.oliociccolella.business\/fr\/vente-huile-d-olive-extra-vierge-italienne\/huile-d-olive-vierge-extra-biologique-coratina-et-ogliarola-barese-bag-in-box\/#itempage","url":"https:\/\/www.oliociccolella.business\/fr\/vente-huile-d-olive-extra-vierge-italienne\/huile-d-olive-vierge-extra-biologique-coratina-et-ogliarola-barese-bag-in-box\/","name":"Organic Cru \u2013 Huile d\u2019olive vierge extra biologique \u2013 Coratina et Ogliarola barese \u2013 Bag in box | Olio Ciccolella","inLanguage":"fr-FR","isPartOf":{"@id":"https:\/\/www.oliociccolella.business\/fr\/#website"},"breadcrumb":{"@id":"https:\/\/www.oliociccolella.business\/fr\/vente-huile-d-olive-extra-vierge-italienne\/huile-d-olive-vierge-extra-biologique-coratina-et-ogliarola-barese-bag-in-box\/#breadcrumblist"},"image":{"@type":"ImageObject","url":"https:\/\/www.oliociccolella.business\/wp-content\/uploads\/2022\/10\/olio-biologico-coratina-e-ogliarola-barese-bag-in-box-3litri.jpg","@id":"https:\/\/www.oliociccolella.business\/fr\/vente-huile-d-olive-extra-vierge-italienne\/huile-d-olive-vierge-extra-biologique-coratina-et-ogliarola-barese-bag-in-box\/#mainImage","width":800,"height":800},"primaryImageOfPage":{"@id":"https:\/\/www.oliociccolella.business\/fr\/vente-huile-d-olive-extra-vierge-italienne\/huile-d-olive-vierge-extra-biologique-coratina-et-ogliarola-barese-bag-in-box\/#mainImage"},"datePublished":"2022-10-07T11:21:11+02:00","dateModified":"2026-01-16T17:10:41+01:00"},{"@type":"Organization","@id":"https:\/\/www.oliociccolella.business\/fr\/#organization","name":"Olio Ciccolella","description":"Olio EVO di qualit\u00e0 superiore","url":"https:\/\/www.oliociccolella.business\/fr\/"},{"@type":"WebSite","@id":"https:\/\/www.oliociccolella.business\/fr\/#website","url":"https:\/\/www.oliociccolella.business\/fr\/","name":"Olio Ciccolella","description":"Olio EVO di qualit\u00e0 superiore","inLanguage":"fr-FR","publisher":{"@id":"https:\/\/www.oliociccolella.business\/fr\/#organization"}}]},"og:locale":"fr_FR","og:site_name":"Olio Ciccolella | Olio EVO di qualit\u00e0 superiore","og:type":"article","og:title":"Organic Cru \u2013 Huile d\u2019olive vierge extra biologique \u2013 Coratina et Ogliarola barese \u2013 Bag in box | Olio Ciccolella","og:url":"https:\/\/www.oliociccolella.business\/fr\/vente-huile-d-olive-extra-vierge-italienne\/huile-d-olive-vierge-extra-biologique-coratina-et-ogliarola-barese-bag-in-box\/","og:image":"https:\/\/www.oliociccolella.business\/wp-content\/uploads\/2022\/10\/olio-biologico-coratina-e-ogliarola-barese-bag-in-box-3litri.jpg","og:image:secure_url":"https:\/\/www.oliociccolella.business\/wp-content\/uploads\/2022\/10\/olio-biologico-coratina-e-ogliarola-barese-bag-in-box-3litri.jpg","og:image:width":800,"og:image:height":800,"article:published_time":"2022-10-07T09:21:11+00:00","article:modified_time":"2026-01-16T16:10:41+00:00","twitter:card":"summary","twitter:title":"Organic Cru \u2013 Huile d\u2019olive vierge extra biologique \u2013 Coratina et Ogliarola barese \u2013 Bag in box | Olio Ciccolella","twitter:image":"https:\/\/www.oliociccolella.business\/wp-content\/uploads\/2022\/10\/olio-biologico-coratina-e-ogliarola-barese-bag-in-box-3litri.jpg"},"aioseo_meta_data":{"post_id":"25869","title":null,"description":null,"keywords":null,"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":{"id":"aioseo-web-page-63690fab9ab87","slug":"web-page","graphName":"WebPage","label":"Web Page","properties":{"type":"WebPage","name":"","description":""}}},"graphName":"ItemPage","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":"{\"article\":{\"articleType\":\"BlogPosting\"},\"course\":{\"name\":\"\",\"description\":\"\",\"provider\":\"\"},\"faq\":{\"pages\":[]},\"product\":{\"reviews\":[]},\"recipe\":{\"ingredients\":[],\"instructions\":[],\"keywords\":[]},\"software\":{\"reviews\":[],\"operatingSystems\":[]},\"webPage\":{\"webPageType\":\"WebPage\"}}","pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2022-10-07 09:21:13","updated":"2026-01-16 16:10:44","seo_analyzer_scan_date":null,"focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.oliociccolella.business\/fr\/\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.oliociccolella.business\/fr\/shop\/\" title=\"Shop\">Shop<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.oliociccolella.business\/fr\/huile-d-olive-extra-vierge-italienne\/blend-fr\/\" title=\"Coratina et Ogliarola barese\">Coratina et Ogliarola barese<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tOrganic Cru \u2013 Huile d\u2019olive vierge extra biologique \u2013 Coratina et Ogliarola barese \u2013 Bag in box\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.oliociccolella.business\/fr\/"},{"label":"Shop","link":"https:\/\/www.oliociccolella.business\/fr\/shop\/"},{"label":"Coratina et Ogliarola barese","link":"https:\/\/www.oliociccolella.business\/fr\/huile-d-olive-extra-vierge-italienne\/blend-fr\/"},{"label":"Organic Cru \u2013 Huile d\u2019olive vierge extra biologique \u2013 Coratina et Ogliarola barese &#8211; Bag in box","link":"https:\/\/www.oliociccolella.business\/fr\/vente-huile-d-olive-extra-vierge-italienne\/huile-d-olive-vierge-extra-biologique-coratina-et-ogliarola-barese-bag-in-box\/"}],"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.oliociccolella.business\/fr\/wp-json\/wp\/v2\/product\/25869","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.oliociccolella.business\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.oliociccolella.business\/fr\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.oliociccolella.business\/fr\/wp-json\/wp\/v2\/media\/26672"}],"wp:attachment":[{"href":"https:\/\/www.oliociccolella.business\/fr\/wp-json\/wp\/v2\/media?parent=25869"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.oliociccolella.business\/fr\/wp-json\/wp\/v2\/product_brand?post=25869"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.oliociccolella.business\/fr\/wp-json\/wp\/v2\/product_cat?post=25869"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.oliociccolella.business\/fr\/wp-json\/wp\/v2\/product_tag?post=25869"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}